{"id":28838,"date":"2021-05-19T21:36:14","date_gmt":"2021-05-19T19:36:14","guid":{"rendered":"https:\/\/awo-fulda.de\/?p=28838"},"modified":"2021-11-23T12:20:43","modified_gmt":"2021-11-23T11:20:43","slug":"linda-kalb-mueller-ueber-ihren-beruflichen-neustart","status":"publish","type":"post","link":"https:\/\/awo-fulda.de\/tr\/2021\/05\/19\/linda-kalb-mueller-ueber-ihren-beruflichen-neustart\/","title":{"rendered":"Linda Kalb-M\u00fcller \u00fcber ihren beruflichen Neustart"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/05\/Header_Linda_KalbMueller_neu-640x360.jpg\" alt=\"\" class=\"wp-image-28884\" width=\"1241\" height=\"698\" srcset=\"https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/05\/Header_Linda_KalbMueller_neu-640x360.jpg 640w, https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/05\/Header_Linda_KalbMueller_neu-480x270.jpg 480w, https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/05\/Header_Linda_KalbMueller_neu-768x432.jpg 768w, https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/05\/Header_Linda_KalbMueller_neu-1536x864.jpg 1536w, https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/05\/Header_Linda_KalbMueller_neu-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 1241px) 100vw, 1241px\" \/><\/figure>\n\n\n\n<h4>\u201eDas Soziale hat schon lange in mir gesteckt\u201c<\/h4>\n<p><strong>Ihr Lebenslauf verlief schnurgerade: Berufsfachschule Ern\u00e4hrung und Hauswirtschaft, dann die FOS Ern\u00e4hrung und Hauswirtschaft, sp\u00e4ter das Studium der \u00d6kotrophologie und anschlie\u00dfend ein Job als Honorarkraft f\u00fcr Koch-Workshops. Wirklich gebrannt hat Linda-Kalbm\u00fcller f\u00fcr diesen Weg aber nicht. Deshalb orientierte sie sich mit 37 Jahren um, studierte Soziale Arbeit und leitet heute f\u00fcr die AWO die Gemeinwesenarbeit in ihrer Heimatstadt Tann. Wie in ihr die Entscheidung gereift ist, den sp\u00e4ten beruflichen Neustart zu wagen, und wie ihr Arbeitsalltag heute aussieht, verr\u00e4t sie im Interview. <\/strong><\/p>\n<p><br \/><strong>Frage:<br \/><\/strong><strong>Du bist in Tann in der Gemeinwesenarbeit t\u00e4tig. Viele k\u00f6nnen sich darunter wahrscheinlich nur wenig vorstellen. Wie w\u00fcrdest du Gemeinwesenarbeit beschreiben?<\/strong><\/p>\n<p>Linda Kalb-M\u00fcller:<br \/>Im Prinzip geht es darum, nicht nur mit einzelnen Menschen zu arbeiten, sondern mit einer Stadt- oder Dorfgemeinschaft, mit einem Quartier. Und auch die anderen in L\u00f6sungen einzubeziehen, wenn Menschen mit Problemen kommen. Es geht auch um Geselligkeit und Miteinander. Es gibt ein afrikanisches Sprichwort: Um ein Kind gro\u00dfzuziehen, braucht man ein ganzes Dorf. Man greift also auf die Ressourcen aus der Gemeinschaft zur\u00fcck.<\/p>\n<p><strong>Kannst du das anhand eines Beispiels erkl\u00e4ren?<\/strong><\/p>\n<p>Wir hatten in Tann ein Sprachcaf\u00e9. Gefl\u00fcchtete Frauen, die wegen der Betreuung ihrer kleinen Kinder zu keinem Sprachkurs nach Fulda kommen konnten, lernten Deutsch von Ehrenamtlichen. So sind auch Kontakte entstanden. Sie sind beispielsweise auch mit ihnen zum Arzt gegangen oder in die Apotheke. Sie unterst\u00fctzten die Frauen sogar bei der Wohnungssuche oder halfen bei der Vermittlung von Jobs an die M\u00e4nner, die zuerst berufst\u00e4tig wurden. Und umgekehrt hat es den Ehrenamtlichen sehr viel Freude bereitet, zu helfen. Es waren meistens \u00e4ltere Damen, deren Kinder und Enkelkinder ganz woanders in Deutschland leben, und die aus dem Ehrenamt sehr viel f\u00fcr sich pers\u00f6nlich an Beziehung, an Kontakt rausgezogen haben.<\/p>\n<p><strong>Ihr k\u00fcmmert euch in Tann also um Gefl\u00fcchtete und Migranten?<\/strong><\/p>\n<p>Mit den Gefl\u00fcchteten sind wir gestartet, weil es in Tann zwei Unterk\u00fcnfte gab. Das war auch der Grund, warum der Landkreis gesagt hat, wir brauchen Gemeinwesenarbeit im l\u00e4ndlichen Raum. 2016 haben wir mit drei Standorten begonnen. Im Januar 2017 bin ich dann nach Tann gekommen. Da haben wir das Sprachcaf\u00e9 und niedrigschwellige Beratung f\u00fcr Gefl\u00fcchtete angeboten. Sp\u00e4ter haben wir auch das Familienzentrum beantragt. F\u00fcr die Tanner Bev\u00f6lkerung war das ein bisschen schwierig.<\/p>\n<p><strong>Wieso?<\/strong><\/p>\n<p>F\u00fcr die Menschen war klar: Die AWO macht was mit Gefl\u00fcchteten, die macht was mit Migranten. Das ist teilweise jetzt noch in den K\u00f6pfen drin, aber es l\u00f6st sich nach und nach auf. In den letzten Sommerferien war es so, dass am Ferienprogramm je zur H\u00e4lfte gefl\u00fcchtete und einheimische Kinder teilnahmen. Es geht auch darum, dass sich die Menschen nicht mehr als Gefl\u00fcchtete f\u00fchlen wollen, sondern als Bewohner von Tann.<\/p>\n<p><strong>Wie ist es euch gelungen, diese Barriere zu \u00fcberwinden?<\/strong><\/p>\n<p>Wir sind auf die Leute zugegangen. Und obwohl wir sehr viel interkulturelle Dinge machen, haben wir das ein bisschen zur\u00fcckgestellt, um nicht den Eindruck zu erwecken, nur mit Gefl\u00fcchteten zu arbeiten.<\/p>\n<p><strong>Wo liegt der Schwerpunkt deiner Arbeit?<\/strong><\/p>\n<p>Ich bin in Tann Standortleitung und Teamleitung von H\u00fcnfeld und Gersfeld. Es geht darum, den besonderen Herausforderungen im l\u00e4ndlichen Raum zu begegnen und bei verschiedenen Aktionen zu kooperieren. Nicht jeder muss das Rad neu erfinden. Beim Tag der Nachbarn haben wir uns beispielsweise abgestimmt und gegenseitig Ideen gegeben, auch wenn ihn jeder Standort etwas anders umsetzt. Bei uns k\u00f6nnen sich die Menschen etwa Pflanz- und Bastelsets abholen, die dann weiterverschenkt werden.<\/p>\n<h4>\u00a0<\/h4>\n<h4>Was die Gemeinwesenarbeit auf dem Land erschwert<\/h4>\n<p><strong>Und welche Aufgaben hast du vor Ort in Tann?<\/strong><\/p>\n<p>Man muss vom Nagel in die Wand klopfen bis zur Verhandlung mit dem B\u00fcrgermeister \u00fcber die Kofinanzierung alles abdecken. Im Moment biete ich Sprechstunden an. Dort k\u00f6nnen die Leute erstmal mit allem kommen, und ich schaue, ob ich ihnen weiterhelfen oder sie an die Migrationsberatung oder Beratungsstellen in Fulda verweisen kann. Wir haben ein Online-Sprachcaf\u00e9, wo wir mit einigen Frauen in Kontakt sind. Daneben koordiniere ich die Ehrenamtsarbeit, die im Moment aber gering ist. Wenn Stadtfeste sind, schaue ich, dass wir Pr\u00e4senz zeigen, k\u00fcmmere mich also um die \u00d6ffentlichkeitsarbeit. Es gibt verschiedene Fr\u00fchst\u00fccke und Spielplatztreffs. In der jetzigen Corona-Zeit haben wir einen B\u00fccher- und Spielverleih, um die Menschen auch mal wieder zu sehen. Es geht darum, Begegnung zu gestalten.<\/p>\n<p><strong>Was f\u00fcr einen Einfluss hat die Corona-Pandemie auf deine Arbeit?<\/strong><\/p>\n<p>Es ist schwierig Begegnungszentren ohne Begegnung zu leiten. Wir haben zwar versucht, Online-Angebote zu machen, merken aber, dass wir nur Leute erreichen, die online relativ fit sind. Wir haben auch ein digitales Caf\u00e9 eingerichtet, wo sich die Menschen zeigen lassen, wie sie zum Beispiel die Zoom-App installieren. F\u00fcr manche ist das aber kein Ersatz. Vor Weihnachten und Ostern sind wir deshalb an die Haust\u00fcren gegangen, haben eine T\u00fcte Pl\u00e4tzchen oder ein Osterei und ein bisschen was S\u00fc\u00dfes vorbeigebracht und uns eine Weile mit den Menschen unterhalten.<\/p>\n<p><strong>Gibt es etwas, das die Gemeinwesenarbeit f\u00fcr dich neben Corona zus\u00e4tzlich erschwert?<\/strong><\/p>\n<p>Die Fahrtzeit. Ich wohne in Fulda und arbeite in Tann. Wenn ich hinfahre, und die Menschen rennen mir die Bude ein, bin ich gl\u00fccklich. Aber manchmal f\u00e4hrt man auch hin, und es ist nichts. Was ich mir f\u00fcr jeden Standort w\u00fcnschen w\u00fcrde ist, dass dort auch Menschen arbeiten, die zumindest in der N\u00e4he wohnen. Denn man bekommt viele Dinge erst mit, wenn man auch in einem Ort lebt. Nicht die offiziellen Nachrichten, sondern Dinge zwischen T\u00fcr und Angel. Das macht auch die Netzwerkarbeit aus. Es ist schwierig, Fachkr\u00e4fte dort hinzubekommen. Ein Beispiel: Es sind neue Frauen nach Tann gekommen, aus Rum\u00e4nien, Bulgarien, die gern einen Deutschkurs machen wollen. Aber ich finde niemanden, der f\u00fcr zwei Stunden nach Tann f\u00e4hrt. Du hast hin und zur\u00fcck 1,5 Stunden Fahrzeit.<\/p>\n<p><strong>Du stammst aus Tann. Was verbindest du mit der Stadt?<\/strong><\/p>\n<p>Kindheitserinnerungen. Ich war mehr als 20 Jahre lang nicht mehr dort, zwar noch in der N\u00e4he, aber mein Lebensmittelpunkt hat sich ver\u00e4ndert. Es war dann interessant, dass man noch viele Gesichter kennt und leicht mit den Leuten ins Gespr\u00e4ch kommt. Denn die AWO ist in Tann, allgemein im l\u00e4ndlichen Raum, weniger bekannt als in der Stadt. Wenn dann ein bekanntes Gesicht da ist, f\u00e4llt es oft leichter, etwas Gemeinschaftliches zu machen.<\/p>\n<p><strong>Wie hast du es empfunden, in deiner alten Heimat beruflich t\u00e4tig zu sein?<\/strong><\/p>\n<p>Es waren gemischte Gef\u00fchle. Auf der einen Seite das Bekannte, Vertraute, wo man doch schnell wieder ansetzen kann. Und dann auch Dinge, wo ich mir denke, genau deswegen bin ich weggegangen. Die Ewiggestrigen, die immer alles mies machen, was neu ist. Du hast eben im l\u00e4ndlichen Raum nicht die Ausweichm\u00f6glichkeiten wie in der Stadt. Je gr\u00f6\u00dfter die Stadt, desto eher findest du die Gemeinschaft, die zu dir passt. Und nichtsdestotrotz gibt es auf dem Land auch die Menschen, die kreative und verr\u00fcckte Ideen haben. Die zu finden und mit ihnen zusammenzuarbeiten, macht dann richtig Spa\u00df.<\/p>\n<p><strong>Die Leute zu finden, mit denen es Spa\u00df macht, eine Aktion zu starten, motiviert dich also an deiner Arbeit. <\/strong><\/p>\n<p>Ja, auf jeden Fall, aber nicht nur das. Vor den letzten Ferienspielen haben wir lang hin und her \u00fcberlegt, ob wir was machen k\u00f6nnen. Wir waren dann in Kleingruppen drau\u00dfen mit Maske, sind ins Testzentrum gegangen, haben also alles getan, um die Aktion abzusichern. Man hat gemerkt, wie ausgehungert die Kinder nach Kontakt waren. Das sind Momente, in denen man merkt, es ist gut, so eine Arbeit zu machen.<\/p>\n<p><strong>Was hilft dir in schwierigen Situationen, die Motivation nicht zu verlieren?<\/strong><\/p>\n<p>Manchmal habe ich Tage, an denen ich denke, ich habe kein Gehalt, sondern Schmerzensgeld bekommen (lacht). Ein bisschen Galgenhumor. Zwar zu sagen, der heutige Tag war Horror, aber zu wissen, der n\u00e4chste wird besser.<\/p>\n<p><strong>Wie findest du an solchen Tagen einen Ausgleich zur Arbeit?<\/strong><\/p>\n<p>Wandern, Fahrradfahren, Spazierengehen. Also sehr viel in der Natur sein. Ich w\u00fcrde auch gern mal wieder tanzen gehen oder Live-Musik h\u00f6ren. Das fehlt mir gerade sehr.<\/p>\n<h4><strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/h4>\n<h4>Wieso Linda Kalb-M\u00fcller den beruflichen Neustart wagte<\/h4>\n<p><strong>Erinnerst du dich noch, wie du zur AWO gekommen bist?<\/strong><\/p>\n<p>Ich habe nochmal relativ sp\u00e4t studiert. Mein erstes Studium war \u00d6kotrophologie, von 1993 bis 2002. In dieser Zeit habe ich meine drei Kinder bekommen. \u00dcber Koch-Workshops bin ich dann in einem Kinder- und Jugendtreff in die p\u00e4dagogische Arbeit eingestiegen, habe aber gemerkt, nur als Honorarkraft zu arbeiten, ist nicht die Super-Perspektive und deshalb von 2010 bis 2013 Soziale Arbeit studiert. W\u00e4hrend des Studiums habe ich am Aschenberg bei der AWO mein Pflichtpraktikum gemacht. Mein Anerkennungsjahr habe ich dann beim Landkreis Fulda gemacht, weil mir die AWO keine Zusage geben konnte. Allerdings war die \u00dcbernahme unsicher.<\/p>\n<p><strong>Also bist du im Anschluss wieder zur\u00fcck zur AWO?<\/strong><\/p>\n<p>Ja, dar\u00fcber war ich auch froh, weil ich gute Erfahrungen mit der AWO gemacht habe. Trotzdem war es gut, mal etwas anderes kennenzulernen und in einer Beh\u00f6rde zu arbeiten. Insgesamt ist die Arbeit dort sehr viel eingeschr\u00e4nkter als bei einem freien Tr\u00e4ger. Die Kreativit\u00e4t und den Freiraum, den ich hier habe, wei\u00df ich deshalb zu sch\u00e4tzen. Bei der AWO habe ich dann 2015 zun\u00e4chst als Familienlotsin angefangen.<\/p>\n<p><strong>Ich stelle mir das finanziell schwierig vor, mit drei Kindern Vollzeit zu studieren. War es das?<\/strong><\/p>\n<p>Wir hatten die klassische Rollenteilung. Mein Mann hat gearbeitet, war der Hauptverdiener. Von daher war es ganz gut machbar. Er hat aber in Frankfurt gearbeitet. Deshalb war ich ein st\u00fcckweit auch wie alleinerziehend, hatte daf\u00fcr aber keine finanziellen Probleme.<\/p>\n<p><strong>Wie kommt man von \u00d6<\/strong><strong>kotrophologie auf Soziale Arbeit?<\/strong><\/p>\n<p>Ich habe die Berufsfachschule im Bereich Ern\u00e4hrung und Hauswirtschaft gemacht, dann die FOS, ebenfalls in Ern\u00e4hrung und Hauswirtschaft. Das Studium hat sich so angef\u00fcgt. Wenn ich ehrlich bin, habe ich mich nie bewusst daf\u00fcr entschieden. Es war eher so, dass mein Vater gesagt hat, du bist eine Frau. Irgendwie war es immer ganz okay und ganz gut gewesen. Ich habe aber gemerkt, so richtig brenne ich nicht daf\u00fcr. Das Soziale hat schon lange in mir gesteckt. Dennoch war es nicht leicht mit 37 bewusst zu sagen, jetzt lege ich meinen Schwerpunkt darauf, studiere nochmal und orientiere mich neu.<\/p>\n<p><strong>Inwiefern war das eine schwierige Entscheidung f\u00fcr dich?<\/strong><\/p>\n<p>Ich wollte nicht so blau\u00e4ugig sein und sagen, ich mache das jetzt, weil es mir Spa\u00df macht, sondern habe mich gefragt, ob ich damit auch Geld verdienen kann. Das ist in der Sozialen Arbeit auch immer so eine Frage. Wir sind die schlechtbezahltesten Akademiker. Bei vielen Bekannten habe ich auch Burn-Outs mitbekommen, weil sie sich f\u00fcr ihre Arbeit aufgeopfert haben. Das im Vorfeld gut zu reflektieren, war wichtig. Ist es das wirklich? Kann ich das? Will ich das? Die Soziale Arbeit bietet aber auch ein breites Spektrum. Wenn ich mit einem bestimmten Klientel nicht mehr arbeiten m\u00f6chte, habe ich die M\u00f6glichkeit, mich anders zu orientieren.<\/p>\n<p><strong>Ist diese Breite der Aufgabenfelder auch ein Vorteil der AWO?<\/strong><\/p>\n<p>Ja, es gibt immer wieder verschiedene Projekte. Man kann immer sagen, ich habe das jetzt eine Zeit lang gemacht, aber nun ist etwas anderes dran. Man hat den Freiraum zu sagen, in diese Richtung m\u00f6chte ich mich entwickeln und schaue deshalb, welche Antr\u00e4ge ich stellen kann und ob das etwas ist, das die AWO insgesamt entwickeln m\u00f6chte. Da erlebe ich unsere Vorgesetzten immer offen f\u00fcr Ideen.<\/p>\n\n\n<p>\u00a0<\/p>\n<p><i>Das Gespr\u00e4ch f\u00fchrte unser Mitarbeiter Toni Spangenberg.<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Ihr Lebenslauf verlief schnurgerade: Berufsfachschule Ern\u00e4hrung und Hauswirtschaft, dann die FOS Ern\u00e4hrung und Hauswirtschaft, sp\u00e4ter das Studium der \u00d6kotrophologie und anschlie\u00dfend ein Job als Honorarkraft f\u00fcr Koch-Workshops. Wirklich gebrannt hat Linda-Kalbm\u00fcller f\u00fcr diesen Weg aber nicht. Deshalb orientierte sie sich mit 37 Jahren um, studierte Soziale Arbeit und leitet heute f\u00fcr die AWO die Gemeinwesenarbeit in ihrer Heimatstadt Tann. Wie in ihr die Entscheidung gereift ist, den sp\u00e4ten beruflichen Neustart zu wagen, und wie ihr Arbeitsalltag heute aussieht, verr\u00e4t sie im Interview.<\/p>\n","protected":false},"author":6,"featured_media":28883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[138],"tags":[],"class_list":["post-28838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-awo-mitarbeitende-im-interview","category-138","description-off"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"tr","enabled_languages":["de","en","fr","ru","ar","tr","fa"],"languages":{"de":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"fa":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts\/28838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/comments?post=28838"}],"version-history":[{"count":13,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts\/28838\/revisions"}],"predecessor-version":[{"id":100624,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts\/28838\/revisions\/100624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/media\/28883"}],"wp:attachment":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/media?parent=28838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/categories?post=28838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/tags?post=28838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}