{"id":123816,"date":"2023-06-06T14:09:44","date_gmt":"2023-06-06T12:09:44","guid":{"rendered":"https:\/\/awo-fulda.de\/?p=123816"},"modified":"2023-06-06T14:10:26","modified_gmt":"2023-06-06T12:10:26","slug":"awo-buecherstudio-samstags-spezial-13-05-2","status":"publish","type":"post","link":"https:\/\/awo-fulda.de\/tr\/2023\/06\/06\/awo-buecherstudio-samstags-spezial-13-05-2\/","title":{"rendered":"AWO-B\u00dcCHERSTUDIO SAMSTAGS-SPEZIAL (10.06.)"},"content":{"rendered":"\n<p><a href=\"https:\/\/awo-fulda.de\/2023\/05\/11\/\"><\/a><\/p>\n\n\n\n<p>Die AWO-Gesch\u00e4ftsstelle \u00f6ffnet ihr B\u00fccherstudio jetzt auch\u00a0<strong>jeden zweiten Samstag im Monat<\/strong>\u00a0f\u00fcr alle B\u00fccherfreunde, die sich gegen kleine Spende mit Lesestoff eindecken m\u00f6chten. Der B\u00fccherbestand wechselt regelm\u00e4\u00dfig, sodass auch beim wiederholten Besuch sicher keine Langeweile aufkommt. Unser Motto bei allem: Der Seele Gutes tun und dabei auch noch anderen helfen! Denn die Spenden f\u00fcr die B\u00fccher kommen vollst\u00e4ndig der Fuldaer Kinderhilfe Uganda zugute (<a href=\"https:\/\/www.fukiuganda.de\/\">https:\/\/www.fukiuganda.de\/<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die AWO-Gesch\u00e4ftsstelle \u00f6ffnet ihr B\u00fccherstudio jetzt auch\u00a0jeden zweiten Samstag im Monat\u00a0f\u00fcr alle B\u00fccherfreunde, die sich gegen kleine Spende mit Lesestoff eindecken m\u00f6chten. Der B\u00fccherbestand wechselt regelm\u00e4\u00dfig, sodass auch beim wiederholten&hellip;<\/p>\n","protected":false},"author":55,"featured_media":123817,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[1],"tags":[],"class_list":["post-123816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-1","description-off"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"tr","enabled_languages":["de","en","fr","ru","ar","tr","fa"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"fa":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts\/123816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/comments?post=123816"}],"version-history":[{"count":3,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts\/123816\/revisions"}],"predecessor-version":[{"id":123830,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/posts\/123816\/revisions\/123830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/media\/123817"}],"wp:attachment":[{"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/media?parent=123816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/categories?post=123816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awo-fulda.de\/tr\/wp-json\/wp\/v2\/tags?post=123816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}