{"id":116303,"date":"2022-10-25T15:43:00","date_gmt":"2022-10-25T13:43:00","guid":{"rendered":"https:\/\/awo-fulda.de\/?p=116303"},"modified":"2022-10-25T16:27:57","modified_gmt":"2022-10-25T14:27:57","slug":"leben-in-der-neuen-heimat-theaterabend-kostenfrei","status":"publish","type":"post","link":"https:\/\/awo-fulda.de\/ru\/2022\/10\/25\/leben-in-der-neuen-heimat-theaterabend-kostenfrei\/","title":{"rendered":"&#8220;Leben in der neuen Heimat&#8221; &#8211; Theaterabend am 3.11. (kostenfrei)"},"content":{"rendered":"\n<p>Anl\u00e4sslich seines Jubil\u00e4ums und der Ausstellung &#8220;75 Jahre AWO &#8211; f\u00fcr ein weltoffenes Fulda&#8221; (5.10.-13.11.2022 vor den Spiegels\u00e4len des Stadtschlosses) sind Sie zu einem kostenfreien Theaterabend eingeladen.<\/p>\n\n\n\n<p>Die Theater-Recherche-Koproduktion &#8220;Fluchtgedanken 3.0&#8221; vom Theater mittendrin und dem Freien Theater Fulda von und mit Barbara Gottwald und Jessica Stukenberg befasst sich mit dem &#8220;Leben in der neuen Heimat&#8221;. Eine Thematik, die das Wirken der AWO ebenfalls bestimmt hat.<\/p>\n\n\n\n<p>Was ist Heimat? Was bedeutet es, seine Heimat zu verlassen &#8211; verlassen zu m\u00fcssen? Ist es m\u00f6glich eine zweite Heimat zu finden? Mit diesen Fragen begaben sich die beiden Theaterfrauen auf Spurensuche und f\u00fchrten Interviews mit drei Personengruppen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>den Heimatvertriebenen nach dem 2. Weltkrieg,<\/li><li>den Gastarbeitern, die von 1955 \u2013 1973 nach Deutschland kamen und denjenigen,<\/li><li>die in den vergangenen 5 Jahren aus Kriegs- und Krisengebieten in Deutschland Zuflucht suchten.<\/li><\/ul>\n\n\n\n<p>Ber\u00fchrende, packende, humorvolle, zuversichtliche, verst\u00f6rende Geschichten\u2026 so unterschiedlich wie ihre Erz\u00e4hlerInnen, sind die L\u00e4nder in denen sie geboren sind und die Gr\u00fcnde, die Heimat zu verlassen.<\/p>\n\n\n\n<p>Zus\u00e4tzliche Informationen:<\/p>\n\n\n\n<p>B\u00fcrgerzentrum Ziehers-S\u00fcd, Dingelstedtstra\u00dfe 12, 36043 Fulda &#8211; Beginn 19 Uhr. <br>Sie k\u00f6nnen gern kurzfristig kommen, wenn m\u00f6glich bitten wir aber um eine Platzreservierung: <br>buero-aktiv@awo-fulda.de oder Tel. 0661 480045-10. <br>Der Eintritt ist frei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anl\u00e4sslich seines Jubil\u00e4ums und der Ausstellung &#8220;75 Jahre AWO &#8211; f\u00fcr ein weltoffenes Fulda&#8221; (5.10.-13.11.2022 vor den Spiegels\u00e4len des Stadtschlosses) sind Sie zu einem kostenfreien Theaterabend eingeladen. Die Theater-Recherche-Koproduktion &#8220;Fluchtgedanken&hellip;<\/p>\n","protected":false},"author":6,"featured_media":116297,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[86],"tags":[],"class_list":["post-116303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presse-berichte","category-86","description-off"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"ru","enabled_languages":["de","en","fr","ru","ar","tr","fa"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"fa":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/posts\/116303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/comments?post=116303"}],"version-history":[{"count":4,"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/posts\/116303\/revisions"}],"predecessor-version":[{"id":117331,"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/posts\/116303\/revisions\/117331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/media\/116297"}],"wp:attachment":[{"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/media?parent=116303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/categories?post=116303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awo-fulda.de\/ru\/wp-json\/wp\/v2\/tags?post=116303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}