{"id":98441,"date":"2021-08-23T11:33:40","date_gmt":"2021-08-23T09:33:40","guid":{"rendered":"https:\/\/awo-fulda.de\/?p=98441"},"modified":"2021-08-23T11:33:42","modified_gmt":"2021-08-23T09:33:42","slug":"psychologische-hilfe-fuer-flutopfer","status":"publish","type":"post","link":"https:\/\/awo-fulda.de\/en\/2021\/08\/23\/psychologische-hilfe-fuer-flutopfer\/","title":{"rendered":"Psychologische Hilfe f\u00fcr Flutopfer"},"content":{"rendered":"\n<p><strong>Deutschlandweit wird gespendet und geholfen. Nun hat der AWO Bundesverband eine kostenfreie Telefonhotline eingerichtet, um Betroffenen und Helfenden aus den Hochwassergebieten unkompliziert und schnell psychologische Unterst\u00fctzung anzubieten.\u00a0<\/strong><\/p>\n<p><strong>Falls Sie Kontakte haben, dann bitte diese Information weitergeben.<\/strong><\/p>\n<p>Ingrid Lebherz, Gesch\u00e4ftsf\u00fchrerin von AWO International, erkl\u00e4rt: \u201eDas Hochwasser hat Existenzen zerst\u00f6rt, Menschen haben Angeh\u00f6rige verloren, der Wiederaufbau wird in manchen Gebieten Jahre dauern. Das ist eine enorme emotionale Belastung und Herausforderung f\u00fcr die Betroffenen, daf\u00fcr braucht es jetzt unkomplizierte Anlaufstellen.\u201c<\/p>\n<p>Jens M. Schubert, Vorstandsvorsitzender des AWO Bundesverbandes, erg\u00e4nzt: \u201eDie AWO-Familie will den Betroffenen in dieser Situation zur Seite stehen \u2013 langfristig beim Wiederaufbau, aber auch jetzt in der akuten Belastungssituation. Deshalb haben wir alle Anstrengungen unternommen, ein gutes, schnelles Beratungs- und Hilfeangebot aufzustellen.\u201c<\/p>\n<p>Auf der Seite <a href=\"https:\/\/awo.org\/hochwasserhilfe\">awo.org\/hochwasserhilfe<\/a> finden Hilfesuchende ab sofort wichtige Anlaufstellen und Telefonnummern. Betroffene und Helfende in den Hochwassergebieten k\u00f6nnen sich zudem an das AWO Hilfetelefon wenden und \u00fcber die emotionalen Belastungen reden. Die <strong>kostenfrei<\/strong>e Hotline der awo lifebalance ist <strong>montags bis freitags in der Zeit von 8 bis 22 Uhr <\/strong>und <strong>samstags und sonntags in der Zeit von 9 bis 16 Uhr<\/strong> mit geschultem Personal besetzt. \u00dcber ein\u00a0<strong>Online-Kontaktformular<\/strong> (<a href=\"www.awo-lifebalance.de\/hochwasser\">www.awo-lifebalance.de\/hochwasser<\/a>) gibt es einen zeitnahen kostenlosen R\u00fcckruf-Service. Bei notwendigen mehreren Beratungen steht eine feste Ansprechperson zur Verf\u00fcgung und empfiehlt im Bedarfsfall auch weiterf\u00fchrende therapeutische Angebote, um die psychischen Belastungen der Hochwasserkatastrophe zu bew\u00e4ltigen.<\/p>\n<p>Alle Gespr\u00e4chsinhalte zwischen der Telefonberatung und den ratsuchenden Personen unterliegen der absoluten Schweigepflicht. Der Schutz aller personenbezogenen Daten nach den geltenden Datenschutzvorschriften ist jederzeit gew\u00e4hrleistet.<\/p>\n<h3><strong>Hotlinenummer 0800 296 0000<\/strong><\/h3>\n<p>(Das Projekt wird durchgef\u00fchrt von der awo lifebalance und unterst\u00fctzt von AWO International und Aktion Deutschland Hilft.)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutschlandweit wird gespendet und geholfen. Nun hat der AWO Bundesverband eine kostenfreie Telefonhotline eingerichtet, um Betroffenen und Helfenden aus den Hochwassergebieten unkompliziert und schnell psychologische Unterst\u00fctzung anzubieten.\u00a0 Falls Sie Kontakte&hellip;<\/p>\n","protected":false},"author":6,"featured_media":67191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-98441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-1","description-off"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["de","en","fr","ru","ar","tr","fa"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"fa":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/98441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/comments?post=98441"}],"version-history":[{"count":2,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/98441\/revisions"}],"predecessor-version":[{"id":98444,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/98441\/revisions\/98444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/media\/67191"}],"wp:attachment":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/media?parent=98441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/categories?post=98441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/tags?post=98441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}