{"id":23856,"date":"2020-08-22T06:34:00","date_gmt":"2020-08-22T04:34:00","guid":{"rendered":"https:\/\/awo-fulda.de\/?p=23856"},"modified":"2020-08-16T18:07:22","modified_gmt":"2020-08-16T16:07:22","slug":"elfenbeinkueste","status":"publish","type":"post","link":"https:\/\/awo-fulda.de\/en\/2020\/08\/22\/elfenbeinkueste\/","title":{"rendered":"Elfenbeink\u00fcste"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>&lt;iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/r24e-9KOMng\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen>&lt;\/iframe><\/code><\/pre>\n\n\n<p><a href=\"https:\/\/youtu.be\/r24e-9KOMng\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/youtu.be\/r24e-9KOMng<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/r24e-9KOMng\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-23856","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-1","description-off"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en","fr","ru","ar","tr","fa"],"languages":{"de":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"fa":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/23856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/comments?post=23856"}],"version-history":[{"count":2,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/23856\/revisions"}],"predecessor-version":[{"id":23858,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/23856\/revisions\/23858"}],"wp:attachment":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/media?parent=23856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/categories?post=23856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/tags?post=23856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}