{"id":23620,"date":"2020-08-22T06:56:36","date_gmt":"2020-08-22T04:56:36","guid":{"rendered":"https:\/\/awo-fulda.de\/?p=23620"},"modified":"2020-08-26T20:38:30","modified_gmt":"2020-08-26T18:38:30","slug":"dankeschoen","status":"publish","type":"post","link":"https:\/\/awo-fulda.de\/en\/2020\/08\/22\/dankeschoen\/","title":{"rendered":"Dankesch\u00f6n"},"content":{"rendered":"\r\n<p class=\"has-medium-font-size\"><strong>Das Internationale M\u00e4rchenfestival 2020 wurde nur m\u00f6glich, weil wir im Vorfeld viele Stunden mit der Produktion von Filmen verbracht haben. Daf\u00fcr m\u00f6chten wir uns ganz herzlich bedanken:<\/strong><br \/><br \/><\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>bei allen Vorleserinnen und Vorlesern*,<br \/>die uns in einer fremden Sprache in eine fremde Welt entf\u00fchrten und die viel Zeit und M\u00fche f\u00fcr die Auswahl passender Bilder und die \u00dcbersetzung der Geschichte aufgewandt haben<\/li>\r\n<li>bei allen Kolleginnen und Kollegen**, <br \/>die sich f\u00fcr die Anmoderation zur Verf\u00fcgung stellten und sowohl unsere sozialen Begegnungsst\u00e4tten als auch den Beitrag pr\u00e4sentierten<\/li>\r\n<li>bei allen anderen, die Ideen beitrugen und im Hintergrund wirkten (z. B. beim Ausdrucken der Bilder, bei der Abrechnung der Belege, bei technischen Fragen und der Organisation)<\/li>\r\n<li>bei unserem Kameramann und Regisseur Oktay Altunnar, den wir als ehrenamtlichen Mitarbeiter in unseren Reihen haben und der sowohl das Equipment als auch das Know-how f\u00fcr die Produktion der Filme lieferte<\/li>\r\n<li>bei der Stadt Fulda und Oberb\u00fcrgermeister Dr. Wingenfeld, der die Schirmherrschaft f\u00fcr das Internationale M\u00e4rchenfestival 2020 \u00fcbernommen hat, das die Vielfalt und Offenheit der Fuldaer B\u00fcrgerinnen und B\u00fcrger dokumentiert<\/li>\r\n<li>bei den Sponsoren des Kutursommers Hessen, die die finanziellen Mittel zur Verf\u00fcgung stellten, ohne die das Ganze nicht m\u00f6glich gewesen w\u00e4re.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p><br \/>Wir haben in unserem Umfeld viele Menschen gefunden, die bereit waren, ihr Heimatland zu repr\u00e4sentieren. Ihre Videos sind hier auf unserer Homepage von A-Z zu sehen. Wenn noch jemand ein M\u00e4rchen aus einem anderen Land beitragen m\u00f6chte, werden wir gelegentlich wieder unser Filmstudio \u00f6ffnen \u2013 einfach melden.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-medium-font-size\"><strong>Danke! Merci! Obrigado! Thank you! \u0634\u0643\u0631\u0627 ! Gracias! \u0421\u043f\u0430\u0441\u0438\u0431\u043e! K\u00f6sz! Terima kasih! Grazie! Hvala!<\/strong><br \/><br \/><\/p>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-table\">\r\n<table>\r\n<tbody>\r\n<tr>\r\n<td><strong>Vorleserinnen und Vorleser*:<\/strong><\/td>\r\n<td>\u00a0<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Afghanistan<\/td>\r\n<td>Qudsia Sharifi<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Angola<\/td>\r\n<td>Manuel Mingos Olivereira<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Brasilien<\/td>\r\n<td>Adriana Oliveira und Werner Althaus (Geb\u00e4rdensprache)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Deutschland<\/td>\r\n<td>Patrick Vasel (historisch\/Gebr\u00fcder Grimm)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Deutschland<\/td>\r\n<td>Marianne L\u00fcbke (Ode\/selbst verfasst)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Elfenbeink\u00fcste<\/td>\r\n<td>Mariame N&#8217;Dakon<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Frankreich<\/td>\r\n<td>Alice Gansen<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>G e b \u00e4 r d e n s p r a c he<\/td>\r\n<td>Werner Althaus (und Adriana Oliveira )<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Guinea (Geschichte)<\/td>\r\n<td>Beret\u00e9 Sidibe<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Guinea (Prosa)<\/td>\r\n<td>Aminata Camara<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Indonesien<\/td>\r\n<td>Septi Panca Sakti<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Iran<\/td>\r\n<td>Shide Baig<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Italien<\/td>\r\n<td>Lisa Mistretta<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Kamerun<\/td>\r\n<td>Nelly Djappa<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Kenia<\/td>\r\n<td>Collette D\u00f6ppner<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Korea<\/td>\r\n<td>Soonja Hesse<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Litauen<\/td>\r\n<td>Monika Cerniauskaite<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Marokko<\/td>\r\n<td>Nabil Alilou<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Mazedonien<\/td>\r\n<td>Elena Veselinova<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Pakistan<\/td>\r\n<td>Tahira Parveen<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Rh\u00f6n (Museumsdorf Tann)<\/td>\r\n<td>Christa Herchenhan-J\u00f6rges (eigene Geschichte\/Rh\u00f6ner Platt)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Russland<\/td>\r\n<td>Olga Polikevic<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Schweiz<\/td>\r\n<td>Erika und Martin Herrlich<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Somalia<\/td>\r\n<td>Wahida Haji<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Syrien<\/td>\r\n<td>Rada Osman<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>T a n z<\/td>\r\n<td>Verein Harmonie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>T\u00fcrkei<\/td>\r\n<td>Kazim Birin, Bahar Baran und Semra Dahan<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Ukraine<\/td>\r\n<td>Irina Stebelska<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Uganda<\/td>\r\n<td>Shamillah Eriasa<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Ungarn<\/td>\r\n<td>Klaudia Taucz und Patrick Vasel<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>W e l t m u s i k<\/td>\r\n<td>Urbain N&#8217;Dakon<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Zimbabwe<\/td>\r\n<td>Nozinhlelo Mpofu<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/figure>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-table\">\r\n<table style=\"width: 100.736%; height: 370px;\">\r\n<tbody>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\"><strong>Kolleginnen und Kollegen**:<\/strong><\/td>\r\n<td style=\"width: 424px; height: 37px;\">\u00a0<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">Gemeinwesenarbeit Ziehers-S\u00fcd<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Christian V\u00f6lkel<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">Gemeinwesenarbeit Ziehers-Nord<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Sara Herchenr\u00f6der<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">Gemeinwesenarbeit in Tann<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Linda Kalb-M\u00fcller<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">Gemeinwesenarbeit Gersfeld und Projekt Kita-Einstieg<\/td>\r\n<td style=\"width: 424px; height: 37px;\">G\u00fclselin Esent\u00fcrk<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">Gemeinwesenarbeit Aschenberg<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Sebastian Cla\u00dfen und Aylin Lubenovic<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">B\u00fcrgerzentrum Aschenberg und korporative Vereine<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Margarete Kl\u00e4r<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">Familientreff S\u00fcdend<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Olga Lichtermann<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">AWO Stadtteiltreff S\u00fcdend und Patenschaftsprojekt<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Sina Ilchmann<\/td>\r\n<\/tr>\r\n<tr style=\"height: 37px;\">\r\n<td style=\"width: 591px; height: 37px;\">Verbandsarbeit und Ehrenamt<\/td>\r\n<td style=\"width: 424px; height: 37px;\">Ilona G\u00f6tz<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/figure>\r\n","protected":false},"excerpt":{"rendered":"<p>Das Internationale M\u00e4rchenfestival 2020 wurde nur m\u00f6glich, weil wir im Vorfeld viele Stunden mit der Produktion von Filmen verbracht haben. Daf\u00fcr m\u00f6chten wir uns ganz herzlich bedanken: bei allen Vorleserinnen&hellip;<\/p>\n","protected":false},"author":6,"featured_media":23613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-23620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-1","description-off"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en","fr","ru","ar","tr","fa"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"fa":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/23620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/comments?post=23620"}],"version-history":[{"count":8,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/23620\/revisions"}],"predecessor-version":[{"id":23989,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/posts\/23620\/revisions\/23989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/media\/23613"}],"wp:attachment":[{"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/media?parent=23620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/categories?post=23620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awo-fulda.de\/en\/wp-json\/wp\/v2\/tags?post=23620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}