{"id":98235,"date":"2021-08-03T09:44:46","date_gmt":"2021-08-03T07:44:46","guid":{"rendered":"https:\/\/awo-fulda.de\/?p=98235"},"modified":"2021-08-03T09:44:48","modified_gmt":"2021-08-03T07:44:48","slug":"erfolgreicher-flohmarkt-am-umweltzentrum-18-07-2021","status":"publish","type":"post","link":"https:\/\/awo-fulda.de\/ar\/2021\/08\/03\/erfolgreicher-flohmarkt-am-umweltzentrum-18-07-2021\/","title":{"rendered":"Erfolgreicher Flohmarkt am Umweltzentrum (18.07.2021)"},"content":{"rendered":"\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\"><img decoding=\"async\" src=\"https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/08\/signal-2021-07-19-183512_004.jpeg\" alt=\"\" \/><\/td>\n<td style=\"width: 33.3333%;\"><img decoding=\"async\" src=\"https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/08\/Flohmarkt-am-Umweltzentrum_18.-Juli-2021-scaled.jpg\" alt=\"\" \/><\/td>\n<td style=\"width: 33.3333%;\"><img decoding=\"async\" src=\"https:\/\/awo-fulda.de\/wp-content\/uploads\/2021\/08\/signal-2021-07-19-183512_002.jpeg\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Am 18.07. haben der AWO Stadtteiltreff S\u00fcdend, die Lutherkirche und YouRoPa e.V. am Umweltzentrum gemeinsam einen Kinder- und Jugendflohmarkt organisiert und mithilfe von vielen flei\u00dfigen Helfer*innen von YouRoPa sowie aus dem S\u00fcdend durchgef\u00fchrt. Neben allerlei Verkaufsst\u00e4nden gab es von der N\u00e4hbar auch einen Kreativstand. Der Flohmarkt war sehr gut besucht und das Wetter hat auch hervorragend mitgespielt! Altes und Gebrauchtes hat neue Besitzer*innen gefunden und wir haben in zahlreiche gl\u00fcckliche Gesichter geschaut \u2013 sowohl auf Verk\u00e4ufer*innen- als auch auf K\u00e4ufer*innen-Seite!<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 18.07. haben der AWO Stadtteiltreff S\u00fcdend, die Lutherkirche und YouRoPa e.V. am Umweltzentrum gemeinsam einen Kinder- und Jugendflohmarkt organisiert und mithilfe von vielen flei\u00dfigen Helfer*innen von YouRoPa sowie aus&hellip;<\/p>\n","protected":false},"author":55,"featured_media":98237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-98235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-1","description-off"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"ar","enabled_languages":["de","en","fr","ru","ar","tr","fa"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"fa":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/posts\/98235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/comments?post=98235"}],"version-history":[{"count":1,"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/posts\/98235\/revisions"}],"predecessor-version":[{"id":98242,"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/posts\/98235\/revisions\/98242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/media\/98237"}],"wp:attachment":[{"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/media?parent=98235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/categories?post=98235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awo-fulda.de\/ar\/wp-json\/wp\/v2\/tags?post=98235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}